{"id":46262,"date":"2025-07-25T18:30:00","date_gmt":"2025-07-25T21:30:00","guid":{"rendered":"https:\/\/www.obispado-mdp.org.ar\/a\/?p=46262"},"modified":"2025-05-01T11:19:11","modified_gmt":"2025-05-01T14:19:11","slug":"evangelio-segun-san-mateo-1324-30-4","status":"publish","type":"post","link":"https:\/\/www.obispado-mdp.org.ar\/a\/evangelio-segun-san-mateo-1324-30-4\/","title":{"rendered":"Evangelio seg\u00fan\u00a0San Mateo\u00a013,24-30."},"content":{"rendered":"\n<p>Jes\u00fas propuso a la gente otra par\u00e1bola:<br>\u00abEl Reino de los Cielos se parece a un hombre que sembr\u00f3 buena semilla en su campo;<br>pero mientras todos dorm\u00edan vino su enemigo, sembr\u00f3 ciza\u00f1a en medio del trigo y se fue.<br>Cuando creci\u00f3 el trigo y aparecieron las espigas, tambi\u00e9n apareci\u00f3 la ciza\u00f1a.<br>Los peones fueron a ver entonces al propietario y le dijeron: &#8216;Se\u00f1or, \u00bfno hab\u00edas sembrado buena semilla en tu campo? \u00bfC\u00f3mo es que ahora hay ciza\u00f1a en \u00e9l?&#8217;.<br>El les respondi\u00f3: &#8216;Esto lo ha hecho alg\u00fan enemigo&#8217;. Los peones replicaron: &#8216;\u00bfQuieres que vayamos a arrancarla?&#8217;.<br>&#8216;No, les dijo el due\u00f1o, porque al arrancar la ciza\u00f1a, corren el peligro de arrancar tambi\u00e9n el trigo.<br>Dejen que crezcan juntos hasta la cosecha, y entonces dir\u00e9 a los cosechadores: Arranquen primero la ciza\u00f1a y \u00e1tenla en manojos para quemarla, y luego recojan el trigo en mi granero'\u00bb.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Extra\u00eddo de la Biblia: Libro del Pueblo de Dios. <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas propuso a la gente otra par\u00e1bola:\u00abEl Reino de los Cielos se parece a un hombre que sembr\u00f3 buena semilla en su campo;pero mientras todos dorm\u00edan vino su enemigo, sembr\u00f3 ciza\u00f1a en medio del trigo y se fue.Cuando creci\u00f3 el trigo y aparecieron las espigas, tambi\u00e9n apareci\u00f3 la ciza\u00f1a.Los peones fueron a ver entonces al [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":31440,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"<!-- wp:paragraph -->\n<p> Al atardecer de ese mismo d\u00eda, el primero de la semana, estando cerradas las puertas del lugar donde se encontraban los disc\u00edpulos, por temor a los jud\u00edos, lleg\u00f3 Jes\u00fas y poni\u00e9ndose en medio de ellos, les dijo: \"\u00a1La paz est\u00e9 con ustedes!\".<br>Mientras dec\u00eda esto, les mostr\u00f3 sus manos y su costado. Los disc\u00edpulos se llenaron de alegr\u00eda cuando vieron al Se\u00f1or.<br>Jes\u00fas les dijo de nuevo: \"\u00a1La paz est\u00e9 con ustedes! Como el Padre me envi\u00f3 a m\u00ed, yo tambi\u00e9n los env\u00edo a ustedes\".<br>Al decirles esto, sopl\u00f3 sobre ellos y a\u00f1adi\u00f3: \"Reciban el Esp\u00edritu Santo.<br>Los pecados ser\u00e1n perdonados a los que ustedes se los perdonen, y ser\u00e1n retenidos a los que ustedes se los retengan\". <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"align\":\"right\"} -->\n<p class=\"has-text-align-right\"><em>Extra\u00eddo de la Biblia: Libro del Pueblo de Dios. <\/em><\/p>\n<!-- \/wp:paragraph -->","_et_gb_content_width":""},"categories":[6],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/posts\/46262"}],"collection":[{"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/comments?post=46262"}],"version-history":[{"count":1,"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/posts\/46262\/revisions"}],"predecessor-version":[{"id":46263,"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/posts\/46262\/revisions\/46263"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/media\/31440"}],"wp:attachment":[{"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/media?parent=46262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/categories?post=46262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/tags?post=46262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}