{"id":46700,"date":"2025-09-23T18:30:00","date_gmt":"2025-09-23T21:30:00","guid":{"rendered":"https:\/\/www.obispado-mdp.org.ar\/a\/?p=46700"},"modified":"2025-07-01T09:24:34","modified_gmt":"2025-07-01T12:24:34","slug":"evangelio-segun-san-lucas-91-6-4","status":"publish","type":"post","link":"https:\/\/www.obispado-mdp.org.ar\/a\/evangelio-segun-san-lucas-91-6-4\/","title":{"rendered":"Evangelio seg\u00fan\u00a0San\u00a0Lucas\u00a09,1-6."},"content":{"rendered":"\n<p>Jes\u00fas convoc\u00f3 a los Doce y les dio poder y autoridad para expulsar a toda clase de demonios y para curar las enfermedades.<br>Y los envi\u00f3 a proclamar el Reino de Dios y a sanar a los enfermos,<br>dici\u00e9ndoles: \u00abNo lleven nada para el camino, ni bast\u00f3n, ni alforja, ni pan, ni dinero, ni tampoco dos t\u00fanicas cada uno.<br>Permanezcan en la casa donde se alojen, hasta el momento de partir.<br>Si no los reciben, al salir de esa ciudad sacudan hasta el polvo de sus pies, en testimonio contra ellos\u00bb.<br>Fueron entonces de pueblo en pueblo, anunciando la Buena Noticia y curando enfermos en todas partes.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Extra\u00eddo de la Biblia: Libro del Pueblo de Dios. <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas convoc\u00f3 a los Doce y les dio poder y autoridad para expulsar a toda clase de demonios y para curar las enfermedades.Y los envi\u00f3 a proclamar el Reino de Dios y a sanar a los enfermos,dici\u00e9ndoles: \u00abNo lleven nada para el camino, ni bast\u00f3n, ni alforja, ni pan, ni dinero, ni tampoco dos t\u00fanicas [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":31453,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"<!-- wp:paragraph -->\n<p> Al atardecer de ese mismo d\u00eda, el primero de la semana, estando cerradas las puertas del lugar donde se encontraban los disc\u00edpulos, por temor a los jud\u00edos, lleg\u00f3 Jes\u00fas y poni\u00e9ndose en medio de ellos, les dijo: \"\u00a1La paz est\u00e9 con ustedes!\".<br>Mientras dec\u00eda esto, les mostr\u00f3 sus manos y su costado. Los disc\u00edpulos se llenaron de alegr\u00eda cuando vieron al Se\u00f1or.<br>Jes\u00fas les dijo de nuevo: \"\u00a1La paz est\u00e9 con ustedes! Como el Padre me envi\u00f3 a m\u00ed, yo tambi\u00e9n los env\u00edo a ustedes\".<br>Al decirles esto, sopl\u00f3 sobre ellos y a\u00f1adi\u00f3: \"Reciban el Esp\u00edritu Santo.<br>Los pecados ser\u00e1n perdonados a los que ustedes se los perdonen, y ser\u00e1n retenidos a los que ustedes se los retengan\". <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"align\":\"right\"} -->\n<p class=\"has-text-align-right\"><em>Extra\u00eddo de la Biblia: Libro del Pueblo de Dios. <\/em><\/p>\n<!-- \/wp:paragraph -->","_et_gb_content_width":""},"categories":[6],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/posts\/46700"}],"collection":[{"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/comments?post=46700"}],"version-history":[{"count":1,"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/posts\/46700\/revisions"}],"predecessor-version":[{"id":46701,"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/posts\/46700\/revisions\/46701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/media\/31453"}],"wp:attachment":[{"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/media?parent=46700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/categories?post=46700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/tags?post=46700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}