{"id":48823,"date":"2026-05-06T18:30:00","date_gmt":"2026-05-06T21:30:00","guid":{"rendered":"https:\/\/www.obispado-mdp.org.ar\/a\/?p=48823"},"modified":"2026-03-01T07:29:18","modified_gmt":"2026-03-01T10:29:18","slug":"evangelio-segun-san-juan-159-11-5","status":"publish","type":"post","link":"https:\/\/www.obispado-mdp.org.ar\/a\/evangelio-segun-san-juan-159-11-5\/","title":{"rendered":"Evangelio seg\u00fan\u00a0San Juan\u00a015,9-11."},"content":{"rendered":"\n<p>Jes\u00fas dijo a sus disc\u00edpulos:<br>\u00abComo el Padre me am\u00f3, tambi\u00e9n yo los he amado a ustedes. Permanezcan en mi amor.<br>Si cumplen mis mandamientos, permanecer\u00e1n en mi amor, como yo cumpl\u00ed los mandamientos de mi Padre y permanezco en su amor.<br>Les he dicho esto para que mi gozo sea el de ustedes, y ese gozo sea perfecto.\u00bb<\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Extra\u00eddo de la Biblia: Libro del Pueblo de Dios. <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas dijo a sus disc\u00edpulos:\u00abComo el Padre me am\u00f3, tambi\u00e9n yo los he amado a ustedes. Permanezcan en mi amor.Si cumplen mis mandamientos, permanecer\u00e1n en mi amor, como yo cumpl\u00ed los mandamientos de mi Padre y permanezco en su amor.Les he dicho esto para que mi gozo sea el de ustedes, y ese gozo sea [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":31450,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"<!-- wp:paragraph -->\n<p> Al atardecer de ese mismo d\u00eda, el primero de la semana, estando cerradas las puertas del lugar donde se encontraban los disc\u00edpulos, por temor a los jud\u00edos, lleg\u00f3 Jes\u00fas y poni\u00e9ndose en medio de ellos, les dijo: \"\u00a1La paz est\u00e9 con ustedes!\".<br>Mientras dec\u00eda esto, les mostr\u00f3 sus manos y su costado. Los disc\u00edpulos se llenaron de alegr\u00eda cuando vieron al Se\u00f1or.<br>Jes\u00fas les dijo de nuevo: \"\u00a1La paz est\u00e9 con ustedes! Como el Padre me envi\u00f3 a m\u00ed, yo tambi\u00e9n los env\u00edo a ustedes\".<br>Al decirles esto, sopl\u00f3 sobre ellos y a\u00f1adi\u00f3: \"Reciban el Esp\u00edritu Santo.<br>Los pecados ser\u00e1n perdonados a los que ustedes se los perdonen, y ser\u00e1n retenidos a los que ustedes se los retengan\". <\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"align\":\"right\"} -->\n<p class=\"has-text-align-right\"><em>Extra\u00eddo de la Biblia: Libro del Pueblo de Dios. <\/em><\/p>\n<!-- \/wp:paragraph -->","_et_gb_content_width":""},"categories":[6],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/posts\/48823"}],"collection":[{"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/comments?post=48823"}],"version-history":[{"count":1,"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/posts\/48823\/revisions"}],"predecessor-version":[{"id":48824,"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/posts\/48823\/revisions\/48824"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/media\/31450"}],"wp:attachment":[{"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/media?parent=48823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/categories?post=48823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.obispado-mdp.org.ar\/a\/wp-json\/wp\/v2\/tags?post=48823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}